{"id":171,"date":"2026-04-16T12:47:06","date_gmt":"2026-04-16T12:47:06","guid":{"rendered":"https:\/\/staging.perspect.it\/mondschein\/kaveau-de\/"},"modified":"2026-04-20T09:24:59","modified_gmt":"2026-04-20T09:24:59","slug":"kaveau","status":"publish","type":"page","link":"https:\/\/ristorantemondschein.it\/de\/kaveau\/","title":{"rendered":"Kaveau"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"tmpl_mbistro.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-171","page","type-page","status-publish","hentry"],"acf":{"bg_intro":234,"bg_img":null,"bg_option":{"bg_position":"right-top","bg_color":"#f0f0f0"},"titolo_prima":"Wine Experience im Mondschein","testo_prima":"<p>EIN \u00dcBERRASCHENDER ORT F\u00dcR EINE UNVERGESSLICHE GESCHMACKSREISE<\/p>","fasce_alternate":[{"titolo":"KAVEAU ist ein wertvoller Ort","testo":"<p>Hier treffen Design und Stil in einer Geschmacksreise aufeinander. Kuratierte Degustationsabende und ma\u00dfgeschneiderte Verkostungsrouten, lokale K\u00f6stlichkeiten, internationale Produkte und Mondschein-Gerichte verschmelzen zu einem einzigartigen Erlebnis.<\/p>","link":"","immagine":235},{"titolo":"KAVEAU ist eine Geschmacksreise","testo":"<p>Hier bewahren wir eine Auswahl internationaler Etiketten neben den lokalen Exzellenzen, die wir so sehr lieben und an die wir fest glauben. Kaveau beherbergt mehr als 1.000 Etiketten, die \u00fcberwiegend von den besten italienischen und internationalen Produzenten stammen.<\/p>","link":"","immagine":236}],"articoli_correlati":[],"colore_sfondo_articoli_correlati":"","titolo_articoli_correlati":"Mehr \u00fcber Mondschein entdecken"},"_links":{"self":[{"href":"https:\/\/ristorantemondschein.it\/de\/wp-json\/wp\/v2\/pages\/171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ristorantemondschein.it\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ristorantemondschein.it\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ristorantemondschein.it\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ristorantemondschein.it\/de\/wp-json\/wp\/v2\/comments?post=171"}],"version-history":[{"count":1,"href":"https:\/\/ristorantemondschein.it\/de\/wp-json\/wp\/v2\/pages\/171\/revisions"}],"predecessor-version":[{"id":237,"href":"https:\/\/ristorantemondschein.it\/de\/wp-json\/wp\/v2\/pages\/171\/revisions\/237"}],"wp:attachment":[{"href":"https:\/\/ristorantemondschein.it\/de\/wp-json\/wp\/v2\/media?parent=171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}